{"id":112,"date":"2022-01-16T07:30:00","date_gmt":"2022-01-16T10:30:00","guid":{"rendered":"http:\/\/arcadei.org\/blog\/?p=112"},"modified":"2022-01-10T18:07:57","modified_gmt":"2022-01-10T21:07:57","slug":"segundo-domingo-despues-de-epifania","status":"publish","type":"post","link":"https:\/\/arcadei.org\/blog\/segundo-domingo-despues-de-epifania\/","title":{"rendered":"Segundo Domingo despu\u00e9s de Epifan\u00eda"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\n<h2 class=\"has-text-align-right wp-block-heading\">Publicado por: Servus Cordis Iesu<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.arcadei.org\/slpw\/email\/_00%20Bloges\/2022\/01%20ENE\/bl-Misa%20Tridentina%2058.jpg?w=584&#038;ssl=1\" alt=\"\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Introito<\/strong><\/p>\n\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">Ad\u00f3rete, oh Dios, toda la tierra, y salmodie en tu honor: diga un salmo a tu nombre, \u00a1oh, Alt\u00edsimo!&nbsp;<em>Salmo:&nbsp;<\/em>Tierra toda, canta jubilosa a Dios, di un salmo a su nombre: dale gloria y alabanza. V. Gloria al Padre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Oraci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Omnipotente y eterno Dios, que gobiernas a un tiempo las cosas celestes y las terrenas: escucha clemente las s\u00faplicas de tu pueblo, y concede tu paz a nuestros tiempos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ep\u00edstola<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lecci\u00f3n de la Ep\u00edstola del Ap\u00f3stol San Pablo a los Romanos (XII, 6-16)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Hermanos: Poseemos dones diferentes, seg\u00fan la gracia que nos ha sido dada: bien el don de profec\u00eda, conforme a la fe; bien el de ministerio, para ejercerlo en el ministerio; el de ense\u00f1anza para el que ense\u00f1a: el de exhortaci\u00f3n para el que exhorta; el de simplicidad para el que distribuye; el de solicitud para el que preside; el de alegr\u00eda para el que ejerce la misericordia. Sea vuestro amor sin disimulo; odiad el mal, apegaos al bien; amaos mutuamente con fraternal caridad; preven\u00edos con mutuo honor; no se\u00e1is perezosos en el cuidado; sed fervorosos de esp\u00edritu; servid al Se\u00f1or; gozaos en la esperanza; sed sufridos en la tribulaci\u00f3n; perseverad en la oraci\u00f3n; asociaos a las necesidades de los santos; seguid la hospitalidad. Bendecid a los que os persigan; bendecid y no maldig\u00e1is. Alegr\u00e1os con los que se alegren, llorad con los que lloren. Sentid todos lo mismo; no ambicion\u00e9is cosas altas, sino acomod\u00e1os a las humildes.<\/em><\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">La paz que en el mundo de los santos es la caracter\u00edstica de los hijos de Dios, es la que crea de igual modo la unidad de la Iglesia ya desde este mundo, pues s\u00f3lo gracias a ella forma un solo cuerpo cuyos diversos miembros mantienen su multiplicidad bajo el influjo de la cabeza y de su jefe \u00fanico, y cuyas funciones tan distintas, son todas ellas dirigidas, dentro de su variedad, por el amor de Cristo-Esposo. La Ep\u00edstola que se nos acaba de leer no tiene m\u00e1s objeto que mostrarnos sometidas al imperio de la caridad, reina de las virtudes, muchas de las aplicaciones de esa paz esencial al cristianismo, especificar detalladamente sus formas y condiciones y adaptar su pr\u00e1ctica a todos los estados sociales y a todas las circunstancias de la vida. Es tal para nuestra Santa Madre la Iglesia, la importancia de estas consideraciones, que volver\u00e1 a tomar este tema, dentro de ocho d\u00edas, el Domingo tercero despu\u00e9s de Epifan\u00eda, continuando el texto, del Ap\u00f3stol en el lugar en que hoy lo deja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora bien, antes de estas sagradas bodas, lejos de la vida divina y de la paz de Dios, que ellas traen al mundo, no hab\u00eda en \u00e9l m\u00e1s que divisi\u00f3n y muerte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gradual<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Se\u00f1or envi\u00f3 su Verbo y los san\u00f3: y los libr\u00f3 de la muerte. V. Alaben al Se\u00f1or sus misericordias: y sus maravillas con los hijos de los hombres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aleluya<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aleluya, aleluya. V. Alabad al Se\u00f1or todos sus \u00c1ngeles: alabadle todos sus ej\u00e9rcitos. Aleluya.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Evangelio<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Continuaci\u00f3n del santo Evangelio seg\u00fan San Juan (II, 1-11)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>En aquel tiempo se celebraron unas bodas en Can\u00e1 de Galilea, y la Madre de Jes\u00fas estaba all\u00ed. Y fue llamado tambi\u00e9n Jes\u00fas y sus disc\u00edpulos a las bodas. Y, faltando el vino, le dijo la Madre de Jes\u00fas: No tienen vino. Y le dijo Jes\u00fas: \u00bfQu\u00e9 nos importa a ti y a m\u00ed, mujer? A\u00fan no ha llegado mi hora. Dijo su Madre a los servidores: Haced cuanto \u00c9l os diga. Y hab\u00eda all\u00ed seis tinajas de piedra, dispuestas para el lavado de los jud\u00edos, en cada una de las cuales cab\u00edan dos o tres c\u00e1ntaros. D\u00edjoles Jes\u00fas: Llenad de agua las tinajas. Y las llenaron hasta el borde. Y d\u00edjoles Jes\u00fas: Sacad ahora y llevad al maestresala. Y llevaron. Y, cuando el maestresala sabore\u00f3 el agua hecha vino, que no sab\u00eda de d\u00f3nde proced\u00eda (peno s\u00ed lo sab\u00edan los sirvientes que hab\u00edan sacado el agua), llam\u00f3 al esposo el maestresala, y le dijo: Todo hombre pone primero el vino bueno: y cuando se han saciado, entonces presenta el peor: mas, t\u00fa has guardado el buen vino hasta ahora. Este primer milagro hizo Jes\u00fas en Can\u00e1 de Galilea: y manifest\u00f3 su gloria, y creyeron en \u00c9l sus disc\u00edpulos.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Oh suerte admirable la nuestra! Dios se ha dignado, como dice el Ap\u00f3stol&nbsp;<em>mostrar las riquezas de su gloria en vasos de misericordia&nbsp;<\/em>(Rom. IX, 23.) Las tinajas de Can\u00e1, s\u00edmbolos de nuestras almas, eran cosas inanimadas y de ning\u00fan modo merec\u00edan tal honor. Jes\u00fas manda a los criados que las llenen de agua; y el agua sirve para purificarlas; pero no cree haber concluido hasta que las&nbsp;<em>ve llenas hasta arriba&nbsp;<\/em>de aquel vino nuevo y celestial, que s\u00f3lo en el reino de su Padre deb\u00eda beberse. De modo semejante se nos comunica a nosotros la caridad divina, que reside en el Sacramento del amor; para no defraudar a su gloria, antes de desposarse con ellas, el divino Emmanuel eleva hasta s\u00ed nuestras almas. Dispong\u00e1monos, pues, para esta uni\u00f3n y seg\u00fan el consejo del Ap\u00f3stol, hag\u00e1monos semejantes a la Virgen pura que est\u00e1 destinada a un Esposo inmaculado. (II, Cor. XI.)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: Dom Prospero Gu\u00e9ranger,&nbsp;<em>El A\u00f1o Lit\u00fargico<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicado por: Servus Cordis Iesu Introito Ad\u00f3rete, oh Dios, toda la tierra, y salmodie en tu honor: diga un salmo a tu nombre, \u00a1oh, Alt\u00edsimo!&nbsp;Salmo:&nbsp;Tierra toda, canta jubilosa a Dios, di un salmo a su nombre: dale gloria y alabanza. &hellip; <a href=\"https:\/\/arcadei.org\/blog\/segundo-domingo-despues-de-epifania\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[80,79,51,65,5,20,42,19,78,52,26,38],"class_list":["post-112","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-adoracion","tag-caridad","tag-espiritualidad","tag-evangelio","tag-iglesia","tag-liturgia","tag-meditacion","tag-paz","tag-progreso-espiritual","tag-sagrada-escritura","tag-vida-de-cristo","tag-virtudes"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pg77Cv-1O","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/comments?post=112"}],"version-history":[{"count":2,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/112\/revisions"}],"predecessor-version":[{"id":135,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/112\/revisions\/135"}],"wp:attachment":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/media?parent=112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/categories?post=112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/tags?post=112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}