{"id":2491,"date":"2025-11-01T07:37:00","date_gmt":"2025-11-01T10:37:00","guid":{"rendered":"https:\/\/arcadei.org\/blog\/?p=2491"},"modified":"2025-11-01T07:37:00","modified_gmt":"2025-11-01T10:37:00","slug":"la-gloria-de-los-santos","status":"publish","type":"post","link":"https:\/\/arcadei.org\/blog\/la-gloria-de-los-santos\/","title":{"rendered":"La gloria de los santos"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\n<p class=\"p1 wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"p1 wp-block-paragraph\"><strong>Fragmento<\/strong>:<\/p>\n\n\n\n<p class=\"p1 wp-block-paragraph\">\u201cLa gloria de los santos es fruto de la gracia, pero tambi\u00e9n de su cooperaci\u00f3n fiel con ella.\u201d<\/p>\n\n\n\n<p class=\"p1 wp-block-paragraph\">\u2014 San Le\u00f3n Magno, Serm\u00f3n 2 sobre Todos los Santos.<\/p>\n\n\n\n<p class=\"p1 wp-block-paragraph\"><strong>Reflexi\u00f3n<\/strong>:<\/p>\n\n\n\n<p class=\"p1 wp-block-paragraph\">Los santos no nacieron perfectos; respondieron con amor a la gracia que Dios les ofrec\u00eda. Cada acto de fidelidad, cada sacrificio silencioso, fue formando en ellos la imagen de Cristo. Tambi\u00e9n nosotros estamos llamados a esa cooperaci\u00f3n diaria que, con la ayuda de la gracia, nos conduce a la santidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fragmento: \u201cLa gloria de los santos es fruto de la gracia, pero tambi\u00e9n de su cooperaci\u00f3n fiel con ella.\u201d \u2014 San Le\u00f3n Magno, Serm\u00f3n 2 sobre Todos los Santos. Reflexi\u00f3n: Los santos no nacieron perfectos; respondieron con amor a la &hellip; <a href=\"https:\/\/arcadei.org\/blog\/la-gloria-de-los-santos\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"La gloria de los santos","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[167],"tags":[8,36],"class_list":["post-2491","post","type-post","status-publish","format-standard","hentry","category-breves","tag-gracia-de-dios","tag-santos"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pg77Cv-Eb","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/2491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/comments?post=2491"}],"version-history":[{"count":1,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/2491\/revisions"}],"predecessor-version":[{"id":2497,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/2491\/revisions\/2497"}],"wp:attachment":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/media?parent=2491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/categories?post=2491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/tags?post=2491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}