{"id":285,"date":"2022-03-05T07:30:00","date_gmt":"2022-03-05T10:30:00","guid":{"rendered":"http:\/\/arcadei.org\/blog\/?p=285"},"modified":"2022-02-24T19:41:17","modified_gmt":"2022-02-24T22:41:17","slug":"senora-de-la-compasion-mujer-de-dolores-reina-de-los-martires","status":"publish","type":"post","link":"https:\/\/arcadei.org\/blog\/senora-de-la-compasion-mujer-de-dolores-reina-de-los-martires\/","title":{"rendered":"Se\u00f1ora de la Compasi\u00f3n, Mujer de Dolores, Reina de los M\u00e1rtires"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\n<h2 class=\"has-text-align-right wp-block-heading\">Publicado por: Servus Cordis Iesu<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/02\/bl-Virgen-de-los-Dolores-44.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"392\" height=\"500\" src=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/02\/bl-Virgen-de-los-Dolores-44.jpg?resize=392%2C500&#038;ssl=1\" alt=\"\" class=\"wp-image-286\" srcset=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/02\/bl-Virgen-de-los-Dolores-44.jpg?w=392&amp;ssl=1 392w, https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/02\/bl-Virgen-de-los-Dolores-44.jpg?resize=235%2C300&amp;ssl=1 235w\" sizes=\"auto, (max-width: 392px) 100vw, 392px\" \/><\/a><\/figure><\/div>\n\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">Se puede ponderar&nbsp;<em>el dolor grande que sentir\u00eda la Virgen&nbsp;<\/em>nuestra Se\u00f1ora&nbsp;<em>cuando oyese los golpes de martillo&nbsp;<\/em>al tiempo que enclavaban a su Hijo; porque un mismo golpe penetraba con el clavo la mano o el pie del Hijo, y traspasaba tambi\u00e9n con agudo dolor el coraz\u00f3n de la Madre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Oh Virgen Soberana!, si a vuestro Hijo cuadra bien el nombre de Var\u00f3n de dolores, a Vos tambi\u00e9n os cuadra otro semejante llam\u00e1ndoos Mujer de Dolores, pues con verdad pod\u00edas decir a todos los que estaban en aquel monte y pasaban por aquel camino: Atended y mirad si hay dolor semejante al m\u00edo.<\/p>\n\n\n\n<ul class=\"wp-block-social-links aligncenter is-layout-flex wp-block-social-links-is-layout-flex\">\n\n\n\n\n\n<\/ul>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Se ha de considerar&nbsp;<em>el dolor que la Virgen Sant\u00edsima padeci\u00f3&nbsp;<\/em>en aquella primera vista de su Hijo: porque en encontr\u00e1ndose los ojos de Cristo y de su Madre, ambos quedar\u00edan eclipsados con suma tristeza: la Madre qued\u00f3 espiritualmente crucificada con la vista de su Hijo, y el Hijo nuevamente afligido con la vista de su Madre; y callando ambos por la vehemencia del dolor, el coraz\u00f3n de cada uno se ocupaba en sentir los dolores que padec\u00eda el otro, doli\u00e9ndose m\u00e1s por ellos que por los propios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ponte, pues \u00a1oh alma m\u00eda!, entre estos dos crucificados, y levanta los ojos al ver al Hijo crucificado con clavos de hierro, y luego b\u00e1jalos a ver a la Madre crucificada con clavos de dolor y compasi\u00f3n, y supl\u00edcales que repartan contigo sus dolores, de modo que t\u00fa tambi\u00e9n est\u00e9s crucificado con ellos por verdadera imitaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Oh Virgen de las v\u00edrgenes, con cu\u00e1nta raz\u00f3n podemos hoy llamaros M\u00e1rtir de los m\u00e1rtires, pues como a todas las v\u00edrgenes excedisteis en la flor de la virginidad, as\u00ed a todos los m\u00e1rtires exced\u00e9is en el fruto del martirio!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias te doy, dulc\u00edsimo Jes\u00fas, por haber encargado a tu Madre que nos tome por hijos, haci\u00e9ndonos con esto tus hermanos. \u00a1Oh Virgen bendit\u00edsima, desde hoy m\u00e1s tengo de deciros confiadamente: Se\u00f1ora m\u00eda, veis aqu\u00ed a vuestro hijo; acordaos que os mand\u00f3 vuestro Hijo unig\u00e9nito me tomases por hijo adoptivo; reconocedme por hijo y mirad por mi remedio!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Oh Virgen Soberana, con cu\u00e1nta verdad pod\u00e9is decir lo que dijo el Ap\u00f3stol: \u00abCumplo en mi carne lo que falta a la Pasi\u00f3n de Cristo por su cuerpo, que es la Iglesia\u00bb! Falt\u00f3 a esta lanzada de Cristo el dolor, porque \u00c9l no la sinti\u00f3, y Vos, Virgen pur\u00edsima, suplisteis esta falta padeciendo y sintiendo el dolor que \u00c9l hab\u00eda de sentir, ofreci\u00e9ndole al Eterno Padre por el cuerpo m\u00edstico de vuestro Hijo, que es su Iglesia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Oh, qu\u00e9 palabras tan tiernas y devotas dir\u00eda!: Dios te salve, \u00a1oh Cruz preciosa!, en cuyos brazos muri\u00f3 el que yo traje siendo ni\u00f1o en los m\u00edos: mayor ventura fue la tuya en esto que la m\u00eda, pues en mis brazos comenz\u00f3 la Redenci\u00f3n del mundo y en los tuyos la acab\u00f3 y perfeccion\u00f3&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entr\u00e1ndose la Virgen en su posada,&nbsp;<em>comenz\u00f3 a llorar en soledad y desamparo<\/em>. Ten\u00eda su alma dividida en muchas partes adonde estaba el Tesoro de su coraz\u00f3n. Una parte estaba en el sepulcro con el cuerpo de su Hijo, meditando los dolores de su Pasi\u00f3n. Otra parte ten\u00eda en el limbo con el Alma del mismo Hijo, contemplando lo que har\u00eda con los padres que all\u00ed estaban; pero mucho m\u00e1s por entonces se le iba el coraz\u00f3n a los dolores, revolvi\u00e9ndolos por su memoria y llorando las causas de ellos, suplicando al Padre Eterno aplicase su fruto a muchos para gloria del que los padeci\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: P. Luis de la Puente,&nbsp;<em>Meditaciones de los misterios de nuestra santa fe<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicado por: Servus Cordis Iesu Se puede ponderar&nbsp;el dolor grande que sentir\u00eda la Virgen&nbsp;nuestra Se\u00f1ora&nbsp;cuando oyese los golpes de martillo&nbsp;al tiempo que enclavaban a su Hijo; porque un mismo golpe penetraba con el clavo la mano o el pie del &hellip; <a href=\"https:\/\/arcadei.org\/blog\/senora-de-la-compasion-mujer-de-dolores-reina-de-los-martires\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[70,27,51,21,42,132,56,25,105,53],"class_list":["post-285","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-combate-espiritual","tag-corredencion","tag-espiritualidad","tag-fe","tag-meditacion","tag-pasion-de-ntro-senor-jesucristo","tag-piedad","tag-prerrogativas-marianas","tag-sma-virgen-maria","tag-union-con-dios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pg77Cv-4B","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/comments?post=285"}],"version-history":[{"count":1,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/285\/revisions"}],"predecessor-version":[{"id":287,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/285\/revisions\/287"}],"wp:attachment":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/media?parent=285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/categories?post=285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/tags?post=285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}