{"id":322,"date":"2022-03-17T07:30:00","date_gmt":"2022-03-17T10:30:00","guid":{"rendered":"http:\/\/arcadei.org\/blog\/?p=322"},"modified":"2022-03-06T12:36:35","modified_gmt":"2022-03-06T15:36:35","slug":"los-frutos-de-la-misa-son-inagotables","status":"publish","type":"post","link":"https:\/\/arcadei.org\/blog\/los-frutos-de-la-misa-son-inagotables\/","title":{"rendered":"Los frutos de la Misa son inagotables"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\n<h2 class=\"has-text-align-right wp-block-heading\">Publicado por: Servus Cordis Iesu<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/03\/bl-Misa-Tridentina-73.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"500\" src=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/03\/bl-Misa-Tridentina-73.jpg?resize=300%2C500&#038;ssl=1\" alt=\"\" class=\"wp-image-323\" srcset=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/03\/bl-Misa-Tridentina-73.jpg?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/03\/bl-Misa-Tridentina-73.jpg?resize=180%2C300&amp;ssl=1 180w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><\/div>\n\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">Los&nbsp;<em>frutos&nbsp;<\/em>de la Misa son inagotables, porque son los frutos mismos del sacrificio de la Cruz. El mismo Jesucristo es quien se ofrece por nosotros a su Padre. Es verdad que despu\u00e9s de la Resurrecci\u00f3n no puede ya merecer; pero ofrece los m\u00e9ritos infinitos adquiridos en la Pasi\u00f3n; y los m\u00e9ritos y las satisfacciones de Jesucristo conservan siempre su valor, al modo como \u00c9l mismo conserva siempre, juntamente con el car\u00e1cter de pont\u00edfice supremo y de mediador universal, la realidad divina de su sacerdocio. Ahora bien, despu\u00e9s de los sacramentos, en la Misa es donde, seg\u00fan el Santo Concilio de Trento, tales m\u00e9ritos nos son particularmente aplicados con mayor plenitud. Y por eso, todo sacerdote ofrece cada Misa no s\u00f3lo por s\u00ed mismo, sino \u201cpor todos los que a ella asisten, por todos los fieles, vivos y difuntos\u201d. \u00a1Tan extensos e inmensos son los frutos de este sacrificio, tan sublime es la gloria que procura a Dios!<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed, pues, cuando sintamos el deseo de reconocer la infinita grandeza de Dios y de ofrecerle, a pesar de nuestra indigencia de criaturas, un homenaje que sea, con seguridad aceptado, ofrezcamos el santo sacrificio, o asistamos a \u00e9l, y presentemos a Dios la divina v\u00edctima. El Padre Eterno recibe de ella, como en el Calvario, un&nbsp;<em>homenaje de valor infinito<\/em>, un homenaje perfectamente digno de sus inefables perfecciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por Jesucristo, Dios y Hombre, inmolado en el altar, se da al Padre todo honor y toda gloria. No hay, en la religi\u00f3n, acci\u00f3n que calme tanto al alma convencida de su nada, y \u00e1vida, no obstante esto, de rendir a Dios homenajes dignos de la grandeza divina. Todos los homenajes reunidos de la creaci\u00f3n y del mundo de los escogidos no dan al Padre Eterno tanta gloria como la que recibe de la ofrenda de su Hijo. Para llegar a comprender el valor de la Misa, es necesaria la fe, esa fe que es a modo de participaci\u00f3n del conocimiento que Dios tiene de s\u00ed mismo y de las cosas divinas. A la luz de la fe, podemos considerar el altar, tal como lo considera el Padre celestial. \u00bfQu\u00e9 es lo que ve el Eterno Padre sobre el altar en que se ofrece el santo sacrificio? Ve \u201cal Hijo de su amor\u201d, al Hijo de sus complacencias, presente, con toda verdad y realidad, y renovando el sacrificio de la Cruz. El precio y valor de las cosas lo tasa Dios en proporci\u00f3n de la gloria que \u00e9stas le tributan; pues bien, en este sacrificio, como en el Calvario, recibe una gloria infinita por mediaci\u00f3n de su amado Hijo; de suerte que no pueden ofrecerse a Dios homenajes m\u00e1s perfectos que \u00e9ste, que los contiene y excede a todos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: Dom Columba Marmion,&nbsp;<em>Jesucristo en sus Misterios<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicado por: Servus Cordis Iesu Los&nbsp;frutos&nbsp;de la Misa son inagotables, porque son los frutos mismos del sacrificio de la Cruz. El mismo Jesucristo es quien se ofrece por nosotros a su Padre. Es verdad que despu\u00e9s de la Resurrecci\u00f3n no &hellip; <a href=\"https:\/\/arcadei.org\/blog\/los-frutos-de-la-misa-son-inagotables\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[110,21,59,20,42,133,122,71,131,55],"class_list":["post-322","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-don-de-dios","tag-fe","tag-gloria-de-dios","tag-liturgia","tag-meditacion","tag-ntro-senor-jesucristo","tag-sacerdocio","tag-sacramentos","tag-sagrado-concilio-tridentino","tag-santa-misa"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pg77Cv-5c","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/comments?post=322"}],"version-history":[{"count":1,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/322\/revisions"}],"predecessor-version":[{"id":324,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/322\/revisions\/324"}],"wp:attachment":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/media?parent=322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/categories?post=322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/tags?post=322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}