{"id":542,"date":"2022-05-26T07:30:00","date_gmt":"2022-05-26T10:30:00","guid":{"rendered":"http:\/\/arcadei.org\/blog\/?p=542"},"modified":"2022-05-16T20:11:47","modified_gmt":"2022-05-16T23:11:47","slug":"jueves-de-la-ascension-de-nuestro-senor","status":"publish","type":"post","link":"https:\/\/arcadei.org\/blog\/jueves-de-la-ascension-de-nuestro-senor\/","title":{"rendered":"Jueves de la Ascensi\u00f3n de Nuestro Se\u00f1or"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\n<h2 class=\"has-text-align-right wp-block-heading\">Publicado por: Servus Cordis Iesu<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/05\/bl-Misa-Tridentina-91.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"406\" height=\"500\" src=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/05\/bl-Misa-Tridentina-91.jpg?resize=406%2C500&#038;ssl=1\" alt=\"\" class=\"wp-image-543\" srcset=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/05\/bl-Misa-Tridentina-91.jpg?w=406&amp;ssl=1 406w, https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/05\/bl-Misa-Tridentina-91.jpg?resize=244%2C300&amp;ssl=1 244w\" sizes=\"auto, (max-width: 406px) 100vw, 406px\" \/><\/a><\/figure><\/div>\n\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">Seg\u00fan una tradici\u00f3n que remonta a los primeros siglos del cristianismo, era el medio d\u00eda la hora en que Jes\u00fas fue elevado sobre la cruz cuando, dirigiendo sobre la concurrencia una mirada de ternura que debi\u00f3 detenerse con complacencia filial sobre Mar\u00eda, elev\u00f3 las manos y les bendijo a todos. En este momento sus pies se desprendieron de la tierra y se elev\u00f3 al cielo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los asistentes le segu\u00edan con la mirada; pero pronto entr\u00f3 en una nube que le ocult\u00f3 a sus ojos. Los disc\u00edpulos ten\u00edan a\u00fan los ojos fijos en el cielo, cuando, de repente, dos \u00c1ngeles vestidos de blanco se presentaron ante ellos y les dijeron: \u201cVarones de Galilea, \u00bfporqu\u00e9 est\u00e1is mirando al cielo? Ese Jes\u00fas que os ha dejado para elevarse al cielo vendr\u00e1 un d\u00eda de la misma manera que le hab\u00e9is visto subir\u201d. Del mismo modo que el Salvador ha subido, debe el Juez descender un d\u00eda: todo el futuro de la Iglesia est\u00e1 comprendido en estos dos t\u00e9rminos. Nosotros vivimos ahora bajo el r\u00e9gimen del Salvador; pues nos ha dicho que \u201cel hijo del hombre no ha venido para juzgar al, mundo, sino para que el mundo sea por \u00c9l salvado\u201d. Y con este fin misericordioso los disc\u00edpulos acaban de recibir la misi\u00f3n de ir por toda la tierra y de convidar a los hombres a la salvaci\u00f3n, mientras tienen tiempo.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Qu\u00e9 inmensa es la tarea que Jes\u00fas les ha confiado, y en el momento en que van a dar comienzo a ella Jes\u00fas les abandona! Les es preciso descender solos del monte de los Olivos de donde ha partido \u00c9l para el cielo. Su coraz\u00f3n, sin embargo, no est\u00e1 triste; tienen con ellos a Mar\u00eda, y la generosidad de esta madre incomparable se comunica a sus almas. Aman a su Maestro; su dicha en adelante consistir\u00e1 en pensar que ha entrado en su descanso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los disc\u00edpulos entraron de nuevo en Jerusal\u00e9n \u201cllenos de una viva alegr\u00eda\u201d, nos dice San Lucas, expresando por esta sola palabra uno de los caracteres de esta fiesta de la Ascensi\u00f3n, impregnada de una tan dulce melancol\u00eda, pero que respira al mismo tiempo m\u00e1s que cualquier otra alegr\u00eda y el triunfo. Esta solemnidad es el cumplimiento de todos los misterios del Redentor y que ha consagrado para siempre el jueves de todas las semanas, d\u00eda tan augusto por la instituci\u00f3n de la santa Eucarist\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Oh nuestro Emmanuel! finalmente has llegado al t\u00e9rmino de tu obra y hoy mismo te vemos entrar en tu reposo. Al comienzo del mundo, empleaste seis d\u00edas para disponer todas las partes del Universo creado por tu poder; despu\u00e9s de lo cual entraste en tu descanso. M\u00e1s tarde, cuando resolviste levantar tu obra ca\u00edda por la malicia del \u00e1ngel rebelde, tu amor te hizo pasar, durante treinta y tres a\u00f1os, por una sucesi\u00f3n sublime de actos por medio de los cuales se obraron nuestra redenci\u00f3n y nuestro restablecimiento en el grado de santidad y de gloria del que hab\u00edamos ca\u00eddo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No olvidaste nada, oh Jes\u00fas, de lo que hab\u00eda sido propuesto en los consejos de la Trinidad, ni de lo que los Profetas hab\u00edan anunciado de ti. Tu Ascensi\u00f3n concluye la misi\u00f3n que has cumplido en tu misericordia. Por segunda vez entras en tu descanso; pero entras con toda la naturaleza humana, llamada en adelante, a tomar parte en honores divinos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya forman parte en las filas de los coros ang\u00e9licos los justos de nuestra raza que has sacado del limbo, pues, al marcharte nos dijiste: \u201cVoy a prepararos un lugar\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Confiados en tu palabra, resueltos a seguirte en todos tus misterios que has cumplido s\u00f3lo por nosotros, a acompa\u00f1arte en la humildad de Bel\u00e9n, en la participaci\u00f3n de los dolores del Calvario, en la resurrecci\u00f3n de Pascua y aspiramos a imitarte tambi\u00e9n, cuando llegue la hora, en tu triunfante Ascensi\u00f3n. Entretanto, nos unimos a los coros de los Ap\u00f3stoles que saludan tu llegada, a nuestros Padres cuya multitud te acompa\u00f1a y te sigue.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fija tu mirada en nosotros, \u00a1oh divino Pastor! no ha llegado a\u00fan el momento de juntarnos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Guarda a tus ovejas y ten cuidado que no se extrav\u00ede ninguna ni sea ingrata a tus cuidados. Conociendo nuestro fin y firmes en el amor y la meditaci\u00f3n de los misterios que nos han conducido al de hoy, tomamos a \u00e9ste como objeto de nuestra espera y el t\u00e9rmino de nuestros deseos. Constituye el fin de tu venida a este mundo, por medio de la cual descendiendo t\u00fa hasta nuestra bajeza, nos ensalzaste hasta hacernos part\u00edcipes de tu grandeza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfPero qu\u00e9 har\u00edamos aqu\u00ed abajo hasta que nos junt\u00e1semos contigo, si la Virtud del Alt\u00edsimo que nos hab\u00e9is prometido no descendiese pronto sobre nosotros, si no nos diese paciencia en el destierro, fidelidad en la ausencia y el amor suficiente para sostener un coraz\u00f3n que suspira por poseerte? \u00a1Ven, pues, oh Esp\u00edritu divino! No nos dejes languidecer, a fin de que nuestra mirada permanezca fija en el cielo donde Jes\u00fas reina y nos espera, y no permitas que el mortal sea tentado, en su cansancio, a arrastrarse por un mundo terrestre en el cual Jes\u00fas no se dejar\u00e1 ver en adelante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: Dom Prospero Gu\u00e9ranger,&nbsp;<em>El A\u00f1o Lit\u00fargico<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicado por: Servus Cordis Iesu Seg\u00fan una tradici\u00f3n que remonta a los primeros siglos del cristianismo, era el medio d\u00eda la hora en que Jes\u00fas fue elevado sobre la cruz cuando, dirigiendo sobre la concurrencia una mirada de ternura que &hellip; <a href=\"https:\/\/arcadei.org\/blog\/jueves-de-la-ascension-de-nuestro-senor\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[30,39,98,145,42,29,91,31,155,105,53,26],"class_list":["post-542","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-amor-a-dios","tag-apostolado","tag-cielo","tag-espiritu-santo","tag-meditacion","tag-misterios-sagrados","tag-redencion","tag-salvacion-eterna","tag-santo-evangelio","tag-sma-virgen-maria","tag-union-con-dios","tag-vida-de-cristo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pg77Cv-8K","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/comments?post=542"}],"version-history":[{"count":1,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/542\/revisions"}],"predecessor-version":[{"id":544,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/542\/revisions\/544"}],"wp:attachment":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/media?parent=542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/categories?post=542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/tags?post=542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}