{"id":554,"date":"2022-05-30T07:30:00","date_gmt":"2022-05-30T10:30:00","guid":{"rendered":"http:\/\/arcadei.org\/blog\/?p=554"},"modified":"2022-05-23T19:39:17","modified_gmt":"2022-05-23T22:39:17","slug":"las-buenas-lecturas","status":"publish","type":"post","link":"https:\/\/arcadei.org\/blog\/las-buenas-lecturas\/","title":{"rendered":"Las buenas lecturas"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\n<h2 class=\"has-text-align-right wp-block-heading\">Publicado por: Servus Cordis Iesu<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/05\/bl-Frodo-01.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"324\" src=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/05\/bl-Frodo-01.jpg?resize=500%2C324&#038;ssl=1\" alt=\"\" class=\"wp-image-555\" srcset=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/05\/bl-Frodo-01.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/05\/bl-Frodo-01.jpg?resize=300%2C194&amp;ssl=1 300w, https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/05\/bl-Frodo-01.jpg?resize=463%2C300&amp;ssl=1 463w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure><\/div>\n\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">Reposar, para el hombre, no es \u00fanicamente distender muellemente los miembros desocupados y abandonarse a un sue\u00f1o restaurador. El reposo humano lleva consigo sanas distracciones, y de ordinario tambi\u00e9n algunas lecturas. Y como actualmente casi no hay familia donde no entre el libro, el op\u00fasculo, el diario, y durante los ocios de las vacaciones las ocasiones de lectura se multiplican, queremos hoy dirigiros alguna breve exhortaci\u00f3n sobre este tema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer hombre que deseoso de comunicar su pensamiento a otros hombres en una forma m\u00e1s duradera que el sonido fugaz de las palabras, grab\u00f3 acaso con un tosco s\u00edlex, en la pared de una caverna, signos convencionales cuya interpretaci\u00f3n determin\u00f3 y explic\u00f3, invent\u00f3 al mismo tiempo la escritura y el arte de la lectura.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Leer es penetrar por medio de signos gr\u00e1ficos, m\u00e1s o menos complicados, en el pensamiento de otro. Ahora bien, como \u201clos pensamientos de los justos son justicia, y los consejos de los imp\u00edos son fraudulentos\u201d, s\u00edguese que algunos libros, como algunas palabras, son manantial de luz, de fuerza, de libertad intelectual y moral, mientras, que otros no traen sino insidias y ocasiones de pecado; tal es de fuerza, de libertad intelectual y moral. Hay, por lo tanto, buenas y malas palabras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La palabra no es con frecuencia sino una l\u00e1mpara; en la noche y en la oscuridad, puede bastar al viajero para encontrar el recto camino, como por otra parte tambi\u00e9n hasta en el sendero m\u00e1s seguro un rayo puede ser suficiente para fulminar a un pasajero incauto; tal es el efecto de la palabra buena o de la mala.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El libro obra menos r\u00e1pidamente, pero su acci\u00f3n se prolonga en el tiempo, es una llama que puede encubrirse bajo las cenizas o arder como una d\u00e9bil lucecilla en la noche, y despu\u00e9s s\u00fabitamente encenderse ben\u00e9fica o devastadora; ser\u00e1 la l\u00e1mpara del santuario, siempre presta a se\u00f1alar al fiel que se acerca, el tabern\u00e1culo santo y su divino Hu\u00e9sped; o bien ser\u00e1 el volc\u00e1n cuyas terribles convulsiones lanzan ciudades enteras en la desolaci\u00f3n y en la muerte. Vosotros dese\u00e1is las conversaciones gratas, las palabras prudentes y confortadoras, y detest\u00e1is con raz\u00f3n la blasfemia y los discursos corruptores. Pues buscad tambi\u00e9n los libros buenos, y odiad los malos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No es nuestra intenci\u00f3n esta ma\u00f1ana, describiros los estragos causados por la mala prensa, sino m\u00e1s bien mostraros el bien que pueden haceros las buenas lecturas, para exhortaros a amarlas y a fomentar su difusi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta es una de las grandes ventajas del buen libro. El amigo cuyas sabias advertencias y justos reproches desde\u00f1\u00e1is, os abandona; pero el libro que hab\u00e9is abandonado, os permanece fiel: olvidado o rechazado en muchas ocasiones, est\u00e1 siempre pronto a volveros a dar la ayuda de sus ense\u00f1anzas, la saludable amargura de sus reproches, la clara luz de sus consejos. Escuchad, pues, sus avisos, tan discretos como directos. La amonestaci\u00f3n, con demasiada frecuencia merecida, que os dirige, el deber, con demasiada frecuencia olvidado, que os recuerda, se los ha dicho ya a muchos, antes que a vosotros; pero no os dir\u00e1 sus nombres, como no revelar\u00e1 a nadie el vuestro; y mientras bajo la l\u00e1mpara silenciosa, a trav\u00e9s de vuestros ojos fijos sobre \u00e9l, os amonesta y os conforta, nadie oir\u00e1 su voz, fuera de vuestro propio coraz\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: S.S. P\u00edo XII,&nbsp;<em>Discurso del 31 de julio de 1940<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicado por: Servus Cordis Iesu Reposar, para el hombre, no es \u00fanicamente distender muellemente los miembros desocupados y abandonarse a un sue\u00f1o restaurador. El reposo humano lleva consigo sanas distracciones, y de ordinario tambi\u00e9n algunas lecturas. Y como actualmente casi &hellip; <a href=\"https:\/\/arcadei.org\/blog\/las-buenas-lecturas\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[39,116,45,61,68,42,75,38],"class_list":["post-554","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-apostolado","tag-conciencia","tag-discernimiento","tag-familia","tag-formacion","tag-meditacion","tag-moral","tag-virtudes"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pg77Cv-8W","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/comments?post=554"}],"version-history":[{"count":1,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/554\/revisions"}],"predecessor-version":[{"id":556,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/554\/revisions\/556"}],"wp:attachment":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/media?parent=554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/categories?post=554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/tags?post=554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}