{"id":585,"date":"2022-06-09T07:30:00","date_gmt":"2022-06-09T10:30:00","guid":{"rendered":"http:\/\/arcadei.org\/blog\/?p=585"},"modified":"2022-05-31T17:24:44","modified_gmt":"2022-05-31T20:24:44","slug":"don-de-ciencia","status":"publish","type":"post","link":"https:\/\/arcadei.org\/blog\/don-de-ciencia\/","title":{"rendered":"Don de Ciencia"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\n<h2 class=\"has-text-align-right wp-block-heading\">Publicado por: Servus Cordis Iesu<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/05\/bl-Espiritu-Santo-33.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"384\" src=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/05\/bl-Espiritu-Santo-33.jpg?resize=500%2C384&#038;ssl=1\" alt=\"\" class=\"wp-image-586\" srcset=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/05\/bl-Espiritu-Santo-33.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/05\/bl-Espiritu-Santo-33.jpg?resize=300%2C230&amp;ssl=1 300w, https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/05\/bl-Espiritu-Santo-33.jpg?resize=391%2C300&amp;ssl=1 391w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">El don de ciencia nos hace sentir y como tocar con la mano la vanidad de toda creatura: pura nada. El hombre, que camina hacia Dios en este universo visible, no debe detenerse en su fugaz belleza; mucho menos quedar cautivo en ella. Todo ha sido hecho para elevarle hasta Dios. El papel del don de ciencia es descubrir a trav\u00e9s de todas las cosas la Faz de Dios. \u00c9l permite al alma evadirse del apresamiento falaz de todo lo creado, hace que no se deje prender en goces transitorios y culpables, que tan pronto convi\u00e9rtense en amargura sin fin. Nos lo ha advertido San Pablo, diciendo que los que gozan de mujer y de todos los falsos bienes de este mundo, tengan mucho cuidado de no eternizar en ellos su coraz\u00f3n. Aun cuando el alma se saciara de ellos, con rapidez fulminante la muerte separa de todo: \u201c\u00a1El tiempo es breve! \u00a1La figura de este mundo pasa!\u201d De ah\u00ed las l\u00e1grimas de los santos al recuerdo de una vida malgastada y del tiempo perdido. Reconciliados con Dios, saborean en su penitencia \u201cla bienaventuranza de las l\u00e1grimas\u201d (Mt 5,5).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las almas puras y desprendidas, para quienes la creatura ha llegado a ser inofensiva, todo eleva hacia Dios. Para el alma virgen, inaccesible a la fascinaci\u00f3n seductora de las creaturas de pecado, la creaci\u00f3n aparece como el magn\u00edfico libro de Dios: \u201cLos cielos narran su gloria\u201d (Sal 18, 2) y hasta el menor \u00e1tomo del universo atestigua su infinito poder. As\u00ed, el don de ciencia, que la Escritura llama \u201cla ciencia de los santos\u201d (Pr 9, 10), libra al alma del gusto malsano de la creatura y -maravillosa transformaci\u00f3n- restituye a la naturaleza misma su sentido original de \u201csigno de Dios\u201d.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cPor este don precioso se le aparece la verdad, conoce lo que Dios pide y lo que reprueba, todo lo que debe buscar y lo que debe huir. Sin la ciencia divina, nuestra vista corre peligro de extraviarse, a causa de las densas tinieblas que tan frecuentemente obscurecen del todo o en parte la inteligencia del hombre. Estas tinieblas provienen, desde luego, de nuestra propia naturaleza, que lleva impresas se\u00f1ales reales de decadencia. Tienen tambi\u00e9n como causa los prejuicios y m\u00e1ximas del mundo que adulteran con frecuencia a los esp\u00edritus tenidos como los m\u00e1s firmes. Finalmente, la acci\u00f3n de Satan\u00e1s, pr\u00edncipe de las tinieblas, va dirigida en gran parte hacia el fin de rodear nuestra alma de obscuridades o de extraviarla sumi\u00e9ndola en falsos resplandores.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>La fe que se nos infundi\u00f3 en el bautismo es la luz de nuestra alma. Por el don de Ciencia, el Esp\u00edritu Santo hace producir a esta virtud rayos muy vivos que disipen nuestras tinieblas. Entonces, las dudas se aclaran, el error se esfuma y aparece la verdad en todo su radiante esplendor. Cada cosa se ve en su verdadera claridad, que es la claridad de la fe. Se descubren los deplorables errores que circulan por el mundo, que seducen a un n\u00famero tan grande de almas y cuya v\u00edctima ha sido quiz\u00e1 frecuentemente uno mismo.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>El don de Ciencia nos revela el fin que Dios se ha propuesto en la creaci\u00f3n, este fin sin el cual los seres no encuentran ni el bien ni el reposo. Nos muestra el uso que debemos hacer de las criaturas que se nos han dado no precisamente como un estorbo, sino como una ayuda eficaz en nuestra marcha hacia Dios. Una vez descubierto el secreto de la vida, nuestro caminar se hace seguro, no vacilamos ya m\u00e1s y nos sentimos dispuestos a abandonar todo camino que no nos conducir\u00eda a nuestro fin. Esta es la Ciencia, don del Esp\u00edritu Santo, que el Ap\u00f3stol tiene en vista, cuando, hablando a los cristianos, les dice: Fuisteis alg\u00fan tiempo tinieblas, pero ahora sois luz en el Se\u00f1or; caminad, pues, como hijos de la luz. De ah\u00ed proviene esta firmeza, este tes\u00f3n de la conducta cristiana. La experiencia puede tener sus fallos algunas veces y el mundo se alarma al pensar en los malos pasos, que hay que temer mucho; es que el mundo ha obrado sin el don de Ciencia. El Se\u00f1or conduce al justo por caminos rectos, y para asegurar sus pasos le ha dado la ciencia de los Santos. Cada d\u00eda se da esta lecci\u00f3n. El cristiano, en medio de la luz sobrenatural, escapa a todos los da\u00f1os, y si no tiene la experiencia propia, posee la experiencia de Dios.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>S\u00e9 bendito, Esp\u00edritu Santo, por esta luz que derramas sobre nosotros y que mantienes con tan amable constancia. No permitas que jam\u00e1s vayamos en busca de otra. Ella sola nos es suficiente; sin ella todo son densas tinieblas. L\u00edbranos de las tristes inconsecuencias de las cuales muchos se dejan seducir imprudentemente. Aceptan un d\u00eda tu direcci\u00f3n, y al siguiente se abandonan a los prejuicios del mundo, llevando una doble vida que no satisface ni al mundo ni a Ti. Nos es necesario, pues, el amor a esta Ciencia que t\u00fa nos has otorgado, si queremos salvarnos; el enemigo de nuestras almas envidia en nosotros esta ciencia salvadora; quisiera suplantarla con sus tinieblas. No permitas, Esp\u00edritu Santo, que realice sus p\u00e9rfidos designios y ay\u00fadanos siempre a discernir lo falso de lo verdadero, lo justo de lo injusto. Que, seg\u00fan la palabra de Jes\u00fas, nuestro ojo sea sencillo, a fin de que todo nuestro cuerpo, es decir, el conjunto de nuestros actos, de nuestros deseos y de nuestros pensamientos se realicen en la luz; l\u00edbranos de ese ojo que Jes\u00fas llama malo y que envuelve en tinieblas todo el cuerpo\u201d&nbsp;<\/em>(Dom Prospero Gu\u00e9ranger,&nbsp;<em>El A\u00f1o Lit\u00fargico<\/em>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: Cf. Marie Michel Philipon,&nbsp;<em>Los Sacramentos en la vida cristiana<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicado por: Servus Cordis Iesu El don de ciencia nos hace sentir y como tocar con la mano la vanidad de toda creatura: pura nada. El hombre, que camina hacia Dios en este universo visible, no debe detenerse en su &hellip; <a href=\"https:\/\/arcadei.org\/blog\/don-de-ciencia\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[126,160,70,45,110,145,51,21,42,81,52,111,53,157,38],"class_list":["post-585","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-auxilios-divinos","tag-ciencia","tag-combate-espiritual","tag-discernimiento","tag-don-de-dios","tag-espiritu-santo","tag-espiritualidad","tag-fe","tag-meditacion","tag-presencia-de-dios","tag-sagrada-escritura","tag-tentaciones","tag-union-con-dios","tag-verdad","tag-virtudes"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pg77Cv-9r","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/comments?post=585"}],"version-history":[{"count":1,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/585\/revisions"}],"predecessor-version":[{"id":587,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/585\/revisions\/587"}],"wp:attachment":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/media?parent=585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/categories?post=585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/tags?post=585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}