{"id":630,"date":"2022-06-23T07:30:00","date_gmt":"2022-06-23T10:30:00","guid":{"rendered":"http:\/\/arcadei.org\/blog\/?p=630"},"modified":"2022-06-19T18:27:16","modified_gmt":"2022-06-19T21:27:16","slug":"el-rey-de-la-familia","status":"publish","type":"post","link":"https:\/\/arcadei.org\/blog\/el-rey-de-la-familia\/","title":{"rendered":"El Rey de la familia"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\n<h2 class=\"has-text-align-right wp-block-heading\">Publicado por: Servus Cordis Iesu<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/06\/bl-Sagrado-Corazon-A71.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"363\" height=\"500\" src=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/06\/bl-Sagrado-Corazon-A71.jpg?resize=363%2C500&#038;ssl=1\" alt=\"\" class=\"wp-image-631\" srcset=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/06\/bl-Sagrado-Corazon-A71.jpg?w=363&amp;ssl=1 363w, https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/06\/bl-Sagrado-Corazon-A71.jpg?resize=218%2C300&amp;ssl=1 218w\" sizes=\"auto, (max-width: 363px) 100vw, 363px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">A vosotros, reci\u00e9n casados, a las palabras de saludo y bendici\u00f3n nos es grato a\u00f1adir una palabra de exhortaci\u00f3n que nos sugieren las circunstancias de esta audiencia que precede en un d\u00eda a la fiesta del Sagrado Coraz\u00f3n de Jes\u00fas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La devoci\u00f3n al Sacrat\u00edsimo Coraz\u00f3n del Redentor del mundo, que en estos \u00faltimos tiempos se ha difundido tan admirablemente por toda la Iglesia en las m\u00e1s elevadas y varias manifestaciones, ha sido establecida y querida por el mismo Salvador divino, al solicitar y sugerir \u00c9l mismo los obsequios con que deseaba fuese honrado su Coraz\u00f3n adorable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jes\u00fas determin\u00f3 el fin de esta querida devoci\u00f3n, cuando en la m\u00e1s c\u00e9lebre de las apariciones a Santa Margarita Mar\u00eda Alacoque prorrumpi\u00f3 en aquellas doloridas palabras: \u201cHe aqu\u00ed el Coraz\u00f3n que tanto ha amado a los hombres y de tantos beneficios les ha colmado, que no ha rehusado nada hasta agotarse y consumarse por testimoniarles su amor: y en cambio no recibe de la mayor parte de ellos sino ingratitudes\u201d.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Amor y reparaci\u00f3n: esto es lo que de modo especial\u00edsimo pide esta devoci\u00f3n; amor para corresponder al que tanto nos am\u00f3; reparaci\u00f3n para resarcir los ultrajes inferidos a este amor infinito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y para incitar a los hombres a que acojan estos deseos suyos, Jes\u00fas se dign\u00f3 confirmarlos con las m\u00e1s largas promesas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre \u00e9stas hay algunas que dicen especial relaci\u00f3n a, las familias cristianas, y por tanto a los esposos, a los padres y a los hijos que ma\u00f1ana vendr\u00e1n a alegrar vuestro hogar dom\u00e9stico. \u201cYo traer\u00e9 y conservar\u00e9 la paz en sus familias. Bendecir\u00e9 las casas en que la imagen de mi Coraz\u00f3n sea expuesta y honrada\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De estas promesas puede decirse que tiene su origen aquella manifestaci\u00f3n de culto familiar que se llama la Consagraci\u00f3n de las familias al Sagrado Coraz\u00f3n de Jes\u00fas, y que en esta circunstancia queremos recomendaros a vosotros, esposos cristianos, que acab\u00e1is de iniciar nuevas familias al pie del altar de Dios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta consagraci\u00f3n significa una entrega completa al divino Coraz\u00f3n: es un reconocimiento de la soberan\u00eda de Nuestro Se\u00f1or sobre la familia: expresa una confiada s\u00faplica para obtener sobre la propia casa sus bendiciones y el cumplimiento de sus promesas. Al consagrarse la familia al Divino Coraz\u00f3n, protesta querer vivir de la vida misma de Jesucristo, y hacer florecer las virtudes que \u00c9l ense\u00f1\u00f3 y vivi\u00f3. \u00c9l preside las reuniones, bendice las empresas, santifica los goces, alivia los afanes, conforta a los moribundos, infunde resignaci\u00f3n a los que aqu\u00ed quedan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed, en vuestras familias consagradas a \u00c9l, Jes\u00fas ser\u00e1 la regla soberana de vuestra conducta y el protector vigilante de vuestros intereses. Que pueda alcanzaros todo eso nuestra paterna Bendici\u00f3n, que de coraz\u00f3n os impartimos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: S.S. P\u00edo XII,&nbsp;<em>Discurso del 14 de junio de 1939<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicado por: Servus Cordis Iesu A vosotros, reci\u00e9n casados, a las palabras de saludo y bendici\u00f3n nos es grato a\u00f1adir una palabra de exhortaci\u00f3n que nos sugieren las circunstancias de esta audiencia que precede en un d\u00eda a la fiesta &hellip; <a href=\"https:\/\/arcadei.org\/blog\/el-rey-de-la-familia\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[30,126,60,51,61,66,139,42,133,19,135,36,64],"class_list":["post-630","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-amor-a-dios","tag-auxilios-divinos","tag-devocion","tag-espiritualidad","tag-familia","tag-hogar","tag-matrimonio","tag-meditacion","tag-ntro-senor-jesucristo","tag-paz","tag-reparacion","tag-santos","tag-voluntad-de-dios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pg77Cv-aa","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/comments?post=630"}],"version-history":[{"count":1,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/630\/revisions"}],"predecessor-version":[{"id":632,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/630\/revisions\/632"}],"wp:attachment":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/media?parent=630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/categories?post=630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/tags?post=630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}