{"id":727,"date":"2022-07-24T07:30:00","date_gmt":"2022-07-24T10:30:00","guid":{"rendered":"http:\/\/arcadei.org\/blog\/?p=727"},"modified":"2022-07-16T18:49:16","modified_gmt":"2022-07-16T21:49:16","slug":"domingo-vii-despues-de-pentecostes","status":"publish","type":"post","link":"https:\/\/arcadei.org\/blog\/domingo-vii-despues-de-pentecostes\/","title":{"rendered":"Domingo VII despu\u00e9s de Pentecost\u00e9s"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\n<h2 class=\"has-text-align-right wp-block-heading\">Publicado por: Servus Cordis Iesu<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/07\/bl-MIsa-Tridentina-A06.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"334\" src=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/07\/bl-MIsa-Tridentina-A06.jpg?resize=500%2C334&#038;ssl=1\" alt=\"\" class=\"wp-image-728\" srcset=\"https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/07\/bl-MIsa-Tridentina-A06.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/07\/bl-MIsa-Tridentina-A06.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/arcadei.org\/blog\/wp-content\/uploads\/2022\/07\/bl-MIsa-Tridentina-A06.jpg?resize=449%2C300&amp;ssl=1 449w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">Oh Dios, cuya providencia no se enga\u00f1a en sus disposiciones: suplic\u00e1moste humildemente apartes todo lo da\u00f1oso, y nos concedas cuanto pueda aprovecharnos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lecci\u00f3n de la Ep\u00edstola del Ap. S. Pablo a los Romanos (VI, 19-23)&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Hermanos: Lo digo humanamente, por la flaqueza de vuestra carne: que, as\u00ed como pusisteis vuestros miembros al servicio de la inmundicia y de la iniquidad, para la iniquidad, as\u00ed pong\u00e1is ahora vuestros miembros al servicio de la justicia, para la santificaci\u00f3n. Porque, cuando erais siervos del pecado, estabais libres de la justicia. Y \u00bfqu\u00e9 fruto sacasteis entonces de aquellas cosas de que ahora os avergonz\u00e1is? Porque el fin de ellas es la muerte. Pero ahora, libertados del pecado, y hechos siervos de Dios, ten\u00e9is por fruto vuestro la santificaci\u00f3n, y por fin la vida eterna. Porque el pago del pecado es la muerte. En cambio, la gracia de Dios es la vida eterna, en Jesucristo, nuestro Se\u00f1or.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La vida del bautizado, que le viene de su uni\u00f3n con Nuestro Se\u00f1or Jesucristo por la fe, es la paz con Dios, la alegr\u00eda y la libertad. Es dos veces libertad: por raz\u00f3n de lo que el bautismo destruye, y por raz\u00f3n de lo que edifica en nosotros. Para comprender esto, importa definir bien lo que es la libertad, y su contraria la servidumbre. Vivo en servidumbre cuando estoy sujeto bajo la dependencia de quien no debo; cuando el tirano ejerce en mis miembros exteriores violencia; cuando me asocia, a pesar m\u00edo, a sus obras malvadas, mientras una parte de m\u00ed, la m\u00e1s alta, protesta contra las bajezas que ejecuta su poder desp\u00f3tico. Entonces verdaderamente s\u00ed que es servidumbre. Pero cuando vivo bajo la dependencia de quien debo; cuando el poder que se ejerce sobre m\u00ed, obra \u00edntimamente, se dirige a la inteligencia y a la voluntad; cuando me hace trabajar con \u00e9l en obras nobles y dignas; cuando me asocia al trabajo de Dios mismo, y bajo su influencia interior, me hace colaborar en un programa de sana moralidad; cuando estoy persuadido que no s\u00f3lo Dios, sino todo lo m\u00e1s elevado de mi alma aplaude la obra que juntos ejecutamos Dios y yo, llamadlo servidumbre si quer\u00e9is, pero para m\u00ed es la suprema libertad, una liberaci\u00f3n absoluta. Ser d\u00f3cil a la inteligencia, es libertad; ser d\u00f3cil a la inteligencia de Dios, es la m\u00e1s absoluta libertad que existe.&nbsp;<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Continuaci\u00f3n del santo Evangelio seg\u00fan S. Mateo (VII, 15-21)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>En aquel tiempo dijo Jes\u00fas a sus disc\u00edpulos: Guardaos de los falsos profetas, que vienen a vosotros con vestidos de ovejas, pero interiormente son lobos rapaces: por sus frutos los conocer\u00e9is. \u00bfAcaso se recogen de las espinas uvas, o de los abrojos higos? As\u00ed, todo: y todo \u00e1rbol malo da malos frutos. No puede el \u00e1rbol bueno dar malos frutos: ni el \u00e1rbol malo puede dar buenos frutos. Todo \u00e1rbol, que no d\u00e9 buen fruto, ser\u00e1 arrancado y arrojado al fuego. As\u00ed que, por sus frutos los conocer\u00e9is. No todo el que me diga: Se\u00f1or, Se\u00f1or, entrar\u00e1 en el reino de los cielos: sino el que haga la voluntad de mi Padre, que est\u00e1 en los cielos, \u00e9se entrar\u00e1 en el reino de los cielos<\/em>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLos conocer\u00e9is por sus frutos\u201d, dice el Evangelio; y la historia confirma la palabra del Se\u00f1or. Bajo la piel de oveja con que quieren enga\u00f1ar a los sencillos, los ap\u00f3stoles del error exhalaban siempre un hedor letal. Sus palabras habilidosas, sus lisonjas interesadas no pueden disimular el vac\u00edo de sus obras. No teng\u00e1is nada com\u00fan con ellos. Los frutos podridos e impuros de las tinieblas y los \u00e1rboles de oto\u00f1o y dos veces muertos que los sostienen en sus ramas secas, tendr\u00e1n el fuego por herencia. Si hab\u00e9is sido tambi\u00e9n vosotros anteriormente tinieblas, ahora que hab\u00e9is llegado a ser luz en el Se\u00f1or por el bautismo, o por el retorno de una conversi\u00f3n sincera, mostraos como tales: producid los frutos de la luz, en toda bondad, justicia y verdad. S\u00f3lo con esta condici\u00f3n pod\u00e9is esperar el reino de los cielos y llamaros ya en este mundo los disc\u00edpulos de esa Sabidur\u00eda del Padre que reclama para s\u00ed hoy nuestro amor. En efecto, dice el Ap\u00f3stol Santiago, como comentando el Evangelio de hoy, \u201c\u00bfacaso la higuera puede dar uvas, o la vid producir higos? \u00bfAcaso la fuente pueda dar agua amarga y dulce a la vez? y ahora, \u00bfqui\u00e9n de nosotros pretende pasar por sabio? Pru\u00e9belo que lo es, mostrando en todas sus obras y en toda su vida la dulzura de la Sabidur\u00eda. Porque hay una sabidur\u00eda amarga y enga\u00f1osa, que no es de lo alto, sino terrena e infernal. La Sabidur\u00eda que viene de arriba, es primeramente casta y pura y adem\u00e1s amiga de la paz, modesta, sin apegarse a su parecer, siempre concorde con los buenos, llena de misericordia y de frutos de buenas obras, que no juzga a los dem\u00e1s, ni tiene segundas intenciones. Los frutos de la justicia que produce, se siembran en la paz, en el seno de los pac\u00edficos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: Dom Prospero Gu\u00e9ranger,&nbsp;<em>El A\u00f1o Lit\u00fargico<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicado por: Servus Cordis Iesu Oh Dios, cuya providencia no se enga\u00f1a en sus disposiciones: suplic\u00e1moste humildemente apartes todo lo da\u00f1oso, y nos concedas cuanto pueda aprovecharnos. Lecci\u00f3n de la Ep\u00edstola del Ap. S. Pablo a los Romanos (VI, 19-23)&nbsp; &hellip; <a href=\"https:\/\/arcadei.org\/blog\/domingo-vii-despues-de-pentecostes\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[74,94,21,8,20,42,75,133,104,19,117,113,52,3,155,53,109],"class_list":["post-727","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-bautismo","tag-conversion","tag-fe","tag-gracia-de-dios","tag-liturgia","tag-meditacion","tag-moral","tag-ntro-senor-jesucristo","tag-oracion","tag-paz","tag-pecado","tag-reino-de-dios","tag-sagrada-escritura","tag-santidad","tag-santo-evangelio","tag-union-con-dios","tag-vida-interior"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pg77Cv-bJ","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/comments?post=727"}],"version-history":[{"count":1,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/727\/revisions"}],"predecessor-version":[{"id":729,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/727\/revisions\/729"}],"wp:attachment":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/media?parent=727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/categories?post=727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/tags?post=727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}