{"id":89,"date":"2022-01-08T07:30:00","date_gmt":"2022-01-08T10:30:00","guid":{"rendered":"http:\/\/arcadei.org\/blog\/?p=89"},"modified":"2022-01-10T18:04:56","modified_gmt":"2022-01-10T21:04:56","slug":"san-pio-x-y-la-sagrada-musica-liturgica-ii","status":"publish","type":"post","link":"https:\/\/arcadei.org\/blog\/san-pio-x-y-la-sagrada-musica-liturgica-ii\/","title":{"rendered":"San P\u00edo X y la Sagrada M\u00fasica Lit\u00fargica (II)"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\n<h2 class=\"has-text-align-right wp-block-heading\">Publicado por: Servus Cordis Iesu&nbsp;<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.arcadei.org\/slpw\/email\/_00%20Bloges\/2022\/01%20ENE\/bl-Liturgia%20Coral%2002.jpg?w=584&#038;ssl=1\" alt=\"\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Instrucci\u00f3n acerca de la M\u00fasica Sagrada<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>I. Principios generales<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">l. Como parte integrante de la liturgia solemne, la m\u00fasica sagrada tiende a su mismo fin, el cual consiste en la gloria de Dios y la santificaci\u00f3n y edificaci\u00f3n de los fieles. La m\u00fasica contribuye a aumentar el decoro y esplendor de las solemnidades religiosas, y as\u00ed como su oficio principal consiste en revestir de adecuadas melod\u00edas el texto lit\u00fargico que se propone a la consideraci\u00f3n de los fieles, de igual manera su propio fin consiste en a\u00f1adir m\u00e1s eficacia al texto mismo, para que por tal medio se excite m\u00e1s la devoci\u00f3n de los fieles y se preparen mejor a recibir los frutos de la gracia, propios de la celebraci\u00f3n de los sagrados misterios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Por consiguiente, la m\u00fasica sagrada debe tener en grado eminente las cualidades propias de la liturgia, conviene a saber: la santidad y la bondad de las formas, de donde nace espont\u00e1neo otro car\u00e1cter suyo: la universalidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debe ser santa y, por lo tanto, excluir todo lo profano, y no s\u00f3lo en s\u00ed misma, sino en el modo con que la interpreten los mismos cantantes.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Debe tener arte verdadero, porque no es posible de otro modo que tenga sobre el \u00e1nimo de quien la oye aquella virtud que se propone la Iglesia al admitir en su liturgia el arte de los sonidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mas a la vez debe ser universal, en el sentido de que, aun concedi\u00e9ndose a toda naci\u00f3n que admita en sus composiciones religiosas aquellas formas particulares que constituyen el car\u00e1cter espec\u00edfico de su propia m\u00fasica, \u00e9ste debe estar de tal modo subordinado a los caracteres generales de la m\u00fasica sagrada, que ning\u00fan fiel procedente de otra naci\u00f3n experimente al o\u00edrla una impresi\u00f3n que no sea buena.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>II. G\u00e9neros de M\u00fasica Sagrada&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. H\u00e1llanse en grado sumo estas cualidades en el canto gregoriano, que es, por consiguiente, el canto propio de la Iglesia romana, el \u00fanico que la Iglesia hered\u00f3 de los antiguos Padres, el que ha custodiado celosamente durante el curso de los siglos en sus c\u00f3dices lit\u00fargicos, el que en algunas partes de la liturgia prescribe exclusivamente, el que estudios recent\u00edsimos han restablecido felizmente en su pureza e integridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por estos motivos, el canto gregoriano fue tenido siempre como acabado modelo de m\u00fasica religiosa, pudiendo formularse con toda raz\u00f3n esta ley general: una composici\u00f3n religiosa ser\u00e1 m\u00e1s sagrada y lit\u00fargica cuanto m\u00e1s se acerque en aire, inspiraci\u00f3n y sabor a la melod\u00eda gregoriana, y ser\u00e1 tanto menos digna del templo cuanto diste m\u00e1s de este modelo soberano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed pues, el antiguo canto gregoriano tradicional deber\u00e1 restablecerse ampliamente en las solemnidades del culto; teni\u00e9ndose por bien sabido que ninguna funci\u00f3n religiosa perder\u00e1 nada de su solemnidad aunque no se cante en ella otra m\u00fasica que la gregoriana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Proc\u00farese, especialmente, que el pueblo vuelva a adquirir la costumbre de usar del canto gregoriano, para que los fieles tomen de nuevo parte m\u00e1s activa en el oficio lit\u00fargico, como sol\u00edan antiguamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4. Las supradichas cualidades se hallan tambi\u00e9n en sumo grado en la polifon\u00eda cl\u00e1sica, especialmente en la de la escuela romana, que en el siglo XVI lleg\u00f3 a la meta de la perfecci\u00f3n con las obras de Pedro Luis de Palestrina, y que luego continu\u00f3 produciendo composiciones de excelente bondad musical y lit\u00fargica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La polifon\u00eda cl\u00e1sica se acerca bastante al canto gregoriano, supremo modelo de toda m\u00fasica sagrada, y por esta raz\u00f3n mereci\u00f3 ser admitida, junto con aquel canto, en las funciones m\u00e1s solemnes de la Iglesia, como son las que se celebran en la capilla pontificia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por consiguiente, tambi\u00e9n esta m\u00fasica deber\u00e1 restablecerse copiosamente en las solemnidades religiosas, especialmente en las bas\u00edlicas m\u00e1s insignes, en las iglesias catedrales y en las de los seminarios e institutos eclesi\u00e1sticos, donde no suelen faltar los medios necesarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5. La Iglesia ha reconocido y fomentado en todo tiempo los progresos de las artes, admitiendo en el servicio del culto cuanto en el curso de los siglos el genio ha sabido hallar de bueno y bello, salva siempre la ley lit\u00fargica; por consiguiente, la m\u00fasica m\u00e1s moderna se admite en la Iglesia, puesto que cuenta con composiciones de tal bondad, seriedad y gravedad, que de ning\u00fan modo son indignas de las solemnidades religiosas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, como la m\u00fasica moderna es principalmente profana, deber\u00e1 cuidarse con mayor esmero que las composiciones musicales de estilo moderno que se admitan en las iglesias no contengan cosa ninguna profana ni ofrezcan reminiscencias de motivos teatrales, y no est\u00e9n compuestas tampoco en su forma externa imitando la factura de las composiciones profanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6. Entre los varios g\u00e9neros de la m\u00fasica moderna, el que aparece menos adecuado a las funciones del culto es el teatral, que durante el pasado siglo estuvo muy en boga, singularmente en Italia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su misma naturaleza, este g\u00e9nero ofrece la m\u00e1xima oposici\u00f3n al canto gregoriano y a la polifon\u00eda cl\u00e1sica, y por ende, a las condiciones m\u00e1s importantes de toda buena m\u00fasica sagrada, adem\u00e1s de que la estructura, el ritmo y el llamado convencionalismo de este g\u00e9nero no se acomodan sino mal\u00edsimamente a las exigencias de la verdadera m\u00fasica lit\u00fargica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: San P\u00edo X, Motu proprio&nbsp;<em>Tra le sollecitudini<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicado por: Servus Cordis Iesu&nbsp; Instrucci\u00f3n acerca de la M\u00fasica Sagrada I. Principios generales l. Como parte integrante de la liturgia solemne, la m\u00fasica sagrada tiende a su mismo fin, el cual consiste en la gloria de Dios y la &hellip; <a href=\"https:\/\/arcadei.org\/blog\/san-pio-x-y-la-sagrada-musica-liturgica-ii\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[39,58,60,54,59,5,20,57,48,55],"class_list":["post-89","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-apostolado","tag-ascetica","tag-devocion","tag-doctrina","tag-gloria-de-dios","tag-iglesia","tag-liturgia","tag-magisterio-de-la-iglesia","tag-papas-santos","tag-santa-misa"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pg77Cv-1r","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/89","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/comments?post=89"}],"version-history":[{"count":2,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/89\/revisions"}],"predecessor-version":[{"id":129,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/89\/revisions\/129"}],"wp:attachment":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/media?parent=89"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/categories?post=89"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/tags?post=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}