{"id":99,"date":"2022-01-10T07:30:00","date_gmt":"2022-01-10T10:30:00","guid":{"rendered":"http:\/\/arcadei.org\/blog\/?p=99"},"modified":"2022-01-10T17:57:20","modified_gmt":"2022-01-10T20:57:20","slug":"san-pio-x-y-la-sagrada-musica-liturgica-iii","status":"publish","type":"post","link":"https:\/\/arcadei.org\/blog\/san-pio-x-y-la-sagrada-musica-liturgica-iii\/","title":{"rendered":"San P\u00edo X y la Sagrada M\u00fasica Lit\u00fargica (III)"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\n<h2 class=\"has-text-align-right wp-block-heading\">Publicado por: Servus Cordis Iesu&nbsp;<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.arcadei.org\/slpw\/email\/_00%20Bloges\/2022\/01%20ENE\/bl-Liber%20Usualis%2001.jpg?w=584&#038;ssl=1\" alt=\"\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><em>III. Texto Lit\u00fargico<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7. La lengua propia de la Iglesia romana es la latina, por lo cual est\u00e1 prohibido que en las solemnidades lit\u00fargicas se cante cosa alguna en lengua vulgar, y mucho m\u00e1s que se canten en lengua vulgar las partes variables o comunes de la misa o el oficio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9. El texto lit\u00fargico ha de cantarse como est\u00e1 en los libros, sin alteraciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>V. Cantores<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">12. Excepto las melod\u00edas propias del celebrante y los ministros, las cuales han de cantarse siempre con m\u00fasica gregoriana, sin ning\u00fan acompa\u00f1amiento de \u00f3rgano, todo lo dem\u00e1s del canto lit\u00fargico es propio del coro de levitas; de manera que los cantores de iglesia, aun cuando sean seglares, hacen propiamente el oficio de coro eclesi\u00e1stico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14. Por \u00faltimo, no se admitan en las capillas de m\u00fasica sino hombres de conocida piedad y probidad de vida, que con su modesta y religiosa actitud durante las solemnidades lit\u00fargicas se muestren dignos del santo oficio que desempe\u00f1an. Ser\u00e1, adem\u00e1s, conveniente que, mientras cantan en la iglesia, los m\u00fasicos vistan h\u00e1bito talar y sobrepelliz, y que, si el coro se halla muy a la vista del p\u00fablico, se le pongan celos\u00edas.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><em>VI. \u00d3rgano e instrumentos<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">15. Si bien la m\u00fasica de la Iglesia es exclusivamente vocal, esto no obstante, tambi\u00e9n se permite la m\u00fasica con acompa\u00f1amiento de \u00f3rgano. En alg\u00fan caso particular, en los t\u00e9rminos debidos y con los debidos miramientos, podr\u00e1n asimismo admitirse otros instrumentos; pero no sin licencia especial del Ordinario, seg\u00fan prescripci\u00f3n del&nbsp;<em>Caeremoniale episcoporum.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">18. En el acompa\u00f1amiento del canto, en los preludios, intermedios y dem\u00e1s pasajes parecidos, el \u00f3rgano debe tocarse seg\u00fan la \u00edndole del mismo instrumento, y debe participar de todas las cualidades de la m\u00fasica sagrada recordadas precedentemente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">19. Est\u00e1 prohibido en las iglesias el uso del piano, como asimismo de todos los instrumentos fragorosos o ligeros, como el tambor, el chinesco, los platillos y otros semejantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">20. Est\u00e1 rigurosamente prohibido que las llamadas bandas de m\u00fasica toquen en las iglesias, y s\u00f3lo en alg\u00fan caso especial, supuesto el consentimiento del Ordinario, ser\u00e1 permitido admitir un n\u00famero juiciosamente escogido, corto y proporcionado al ambiente, de instrumentos de aire, que vayan a ejecutar composiciones o acompa\u00f1ar al canto, con m\u00fasica escrita en estilo grave, conveniente y en todo parecida a la del \u00f3rgano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">21. En las procesiones que salgan de la iglesia, el Ordinario podr\u00e1 permitir que asistan las bandas de m\u00fasica, con tal de que no ejecuten composiciones profanas. Ser\u00eda de apetecer que en tales ocasiones las dichas m\u00fasicas se limitasen a acompa\u00f1ar alg\u00fan himno religioso, escrito en lat\u00edn o en lengua vulgar, cantado por los cantores y las piadosas cofrad\u00edas que asistan a la procesi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>VII. Extensi\u00f3n de la M\u00fasica religiosa<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">22. No es l\u00edcito que por raz\u00f3n del canto o la m\u00fasica se haga esperar al sacerdote en el altar m\u00e1s tiempo del que exige la liturgia.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">23. En general, ha de condenarse como abuso grav\u00edsimo que, en las funciones religiosas, la liturgia quede en lugar secundario y como al servicio de la m\u00fasica, cuando la m\u00fasica forma parte de la liturgia y no es sino su humilde sierva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>VIII. Medios principales<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">25. En los seminarios de cl\u00e9rigos y en los institutos eclesi\u00e1sticos se ha de cultivar con amor y diligencia, conforme a las disposiciones del Tridentino, el ya alabado canto gregoriano tradicional, y en esta materia sean los superiores generosos de est\u00edmulos y encomios con sus j\u00f3venes s\u00fabditos. Asimismo, promu\u00e9vase con el clero, donde sea posible, la fundaci\u00f3n de una Schola cantorum para la ejecuci\u00f3n de la polifon\u00eda sagrada y de la buena m\u00fasica lit\u00fargica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">26. En las lecciones de liturgia, moral y derecho can\u00f3nico que se explican a los estudiantes de teolog\u00eda, no dejen de tocarse aquellos puntos que m\u00e1s especialmente se refieren a los principios fundamentales y las reglas de la m\u00fasica sagrada, y proc\u00farese completar la doctrina con instrucciones especiales acerca de la est\u00e9tica del arte religioso, para que los cl\u00e9rigos no salgan del seminario ayunos de estas nociones, tan necesarias a la plena cultura eclesi\u00e1stica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">28. Es muy importante que la Iglesia misma provea a la instrucci\u00f3n de sus maestros, organistas y cantores, conforme a los verdaderos principios del arte sagrado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>IX. Conclusi\u00f3n<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">29. Por \u00faltimo, se recomienda a los maestros de capilla, cantores, eclesi\u00e1sticos, superiores de seminarios, de institutos eclesi\u00e1sticos y de comunidades religiosas, a los p\u00e1rrocos y rectores de iglesias, a los can\u00f3nigos de colegiatas y catedrales, y sobre todo a los Ordinarios diocesanos, que favorezcan con todo celo estas prudentes reformas, desde hace mucho deseadas y por todos un\u00e1nimemente pedidas, para que no caiga en desprecio la misma autoridad de la Iglesia, que repetidamente las ha propuesto y ahora de nuevo las inculca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: San P\u00edo X, Motu proprio&nbsp;<em>Tra le sollecitudini<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicado por: Servus Cordis Iesu&nbsp; III. Texto Lit\u00fargico 7. La lengua propia de la Iglesia romana es la latina, por lo cual est\u00e1 prohibido que en las solemnidades lit\u00fargicas se cante cosa alguna en lengua vulgar, y mucho m\u00e1s que &hellip; <a href=\"https:\/\/arcadei.org\/blog\/san-pio-x-y-la-sagrada-musica-liturgica-iii\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[12,69,54,68,40,5,20,57,48,56,55],"class_list":["post-99","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-celo-santo","tag-cultura","tag-doctrina","tag-formacion","tag-formacion-intelectual","tag-iglesia","tag-liturgia","tag-magisterio-de-la-iglesia","tag-papas-santos","tag-piedad","tag-santa-misa"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pg77Cv-1B","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/99","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/comments?post=99"}],"version-history":[{"count":2,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/99\/revisions"}],"predecessor-version":[{"id":120,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/posts\/99\/revisions\/120"}],"wp:attachment":[{"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/media?parent=99"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/categories?post=99"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arcadei.org\/blog\/wp-json\/wp\/v2\/tags?post=99"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}